{"id":856,"count":0,"description":"Erleben Sie den Inbegriff von Finesse und Kraft mit der Nike KD (Kevin Durant) Kollektion bei BaseReps. Diese Kollektion repr\u00e4sentiert die Entwicklung von Kevin Durant, einem der erfolgreichsten Scorer in der Basketballgeschichte, und ist ein Schaufenster der Pr\u00e4zision, Anpassungsf\u00e4higkeit und des Stils. Jeder Sneaker ist auf die einzigartige Spielweise von KD zugeschnitten und wurde f\u00fcr fl\u00fcssige Bewegungen, scharfe Sch\u00fcsse und un\u00fcbertroffenen Komfort auf dem Spielfeld entwickelt. Die Designs erz\u00e4hlen auch Durants pers\u00f6nliche Geschichte, von seinen bescheidenen Anf\u00e4ngen in Maryland bis zu seinem kometenhaften Aufstieg in der NBA. Die Nike KD Kollektion steht als Symbol f\u00fcr Hingabe, Widerstandsf\u00e4higkeit und den schieren Willen zum Erfolg. Tauchen Sie ein in eine Kollektion, die die Reise und den Geist eines wahren Basketball-Maestros feiert.","link":"https:\/\/basereps.com\/de\/nike-reps-kd-schuhe\/","name":"Nike Reps KD Schuhe","slug":"nike-reps-kd-schuhe","taxonomy":"product_cat","parent":855,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat\/855"}],"wp:post_type":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product?product_cat=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}