{"id":828,"count":2,"description":"Reisen Sie ins Jahr 1990 mit der Air Jordan 5 Reps Kollektion bei BaseReps. Der Air Jordan 5 Reps, eine Fusion aus Innovation und Stil, war ein weiteres Meisterwerk aus Tinker Hatfields Design-Portfolio. Der AJ5 wurde von Kampfflugzeugen aus dem Zweiten Weltkrieg inspiriert und zeichnete sich durch ein unverwechselbares Haifischzahn-Design auf der Zwischensohle und eine reflektierende Zunge aus, wodurch er sofort erkennbar war. Die Einf\u00fchrung eines geformten Kn\u00f6chelkragens und eines Schn\u00fcrverschlusses f\u00fcr eine sichere Passform stellte eine Mischung aus Form und Funktion dar. W\u00e4hrend Michael Jordans Karriere wurde der Air Jordan 5 Reps zum Synonym f\u00fcr seine Dominanz in der Luft und sein Flair. Feiern Sie das Verm\u00e4chtnis eines Sneakers, der die goldene \u00c4ra des Basketballs verk\u00f6rpert und weiterhin Generationen beeinflusst.","link":"https:\/\/basereps.com\/de\/air-jordan-5-reps-schuhe\/","name":"Air Jordan 5 Reps Schuhe","slug":"air-jordan-5-reps-schuhe","taxonomy":"product_cat","parent":824,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat\/824"}],"wp:post_type":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product?product_cat=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}