{"id":689,"count":0,"description":"Die Damen Strandmode Kollektion pr\u00e4sentiert eine stilvolle und vielseitige Auswahl an Bekleidung, die speziell f\u00fcr sonnige Tage am Strand gestaltet ist. Diese Kollektion umfasst eine breite Palette an Outfits, von trendigen Badeanz\u00fcgen und luftigen Strandkleidern bis hin zu l\u00e4ssigen Shorts und bequemen Tuniken. Jedes St\u00fcck vereint modisches Design mit praktischer Funktionalit\u00e4t, um Frauen ein komfortables und stilvolles Strandvergn\u00fcgen zu erm\u00f6glichen. Mit verschiedenen Farben, Mustern und Schnitten bietet die Damen Strandmode Kollektion f\u00fcr jeden Geschmack und Anlass das passende Outfit, damit Frauen ihre Zeit am Strand in vollen Z\u00fcgen genie\u00dfen k\u00f6nnen.","link":"https:\/\/basereps.com\/de\/damen-strandmode\/","name":"Damen Strandmode","slug":"damen-strandmode","taxonomy":"product_cat","parent":688,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product_cat\/688"}],"wp:post_type":[{"href":"https:\/\/basereps.com\/de\/wp-json\/wp\/v2\/product?product_cat=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}